{"id":10303,"date":"2024-09-27T12:09:35","date_gmt":"2024-09-27T16:09:35","guid":{"rendered":"https:\/\/montrealcentreville.ca\/?post_type=what-to-do&#038;p=10303"},"modified":"2024-09-27T16:26:52","modified_gmt":"2024-09-27T20:26:52","slug":"les-jardins-du-centre-ville-free-concerts-all-summer","status":"publish","type":"what-to-do","link":"https:\/\/montrealcentreville.ca\/en\/what-to-do\/les-jardins-du-centre-ville-free-concerts-all-summer\/","title":{"rendered":"Les Jardins du centre-ville: Free Concerts All Summer!"},"content":{"rendered":"\n    <section class=\"wysiwyg || relative section slate\">\n        <div class=\"circle-big || absolute top-10 -left-[50px] || md:top-20 md:-left-[100px] xl:-left-[150px]\"><\/div>\n        \n<span class=\"absolute top-0 left-0\" ><\/span>        <div class=\"wrapper || relative flex justify-center \">\n            <div class=\"wysiwyg-container || w-full \">\n                <h2>\ud83c\udfb6 A big finale for the summer concerts at Victoria Square and Phillips Square! \ud83c\udf89<\/h2>\n<p>From June to September, many of you enjoyed the free concerts that animated these two iconic downtown locations. Thank you all for your presence and enthusiasm, which made every musical moment a true success! \ud83d\ude4c<br \/>\nWhether it was during lunchtime at Victoria Square or after-work hours at Phillips Square, these moments of outdoor music allowed both young and old to relax and savor the summer together.<br \/>\nA huge thank you to all the talented artists who lit up these spaces with their varied and memorable performances, as well as to the downtown businesses that made this programming possible. \ud83c\udfa4\ud83c\udfb8<\/p>\n<p><strong>We look forward to new adventures next year!<\/strong><\/p>\n<h2>\ud83d\udcf8 A look back at a vibrant summer filled with music and connections!<\/h2>\n            <\/div>\n                    <\/div>\n    <\/section>\n\n\n    <section class=\"carrousel section overflow-hidden slate\">\n        \n<span class=\"absolute top-0 left-0\" ><\/span>        <div class=\"wrapper\">\n                        <div class=\"swiper-simple || relative mt-16\">\n                <div class=\"swiper-wrapper || items-center\">\n                                                    <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-640x640.jpg\" class=\"\" alt=\"Concert_square_Phillips_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/8-1.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-640x640.jpg\" class=\"\" alt=\"Concert_square_Phillips_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/6-1.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-640x640.jpg\" class=\"\" alt=\"Concert_square_Phillips_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/5-4.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-640x640.jpg\" class=\"\" alt=\"Concert_square_Phillips_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/7.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-640x640.jpg\" class=\"\" alt=\"Concert_square_Victoria_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/3-4.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-640x640.jpg\" class=\"\" alt=\"Concert_square_Victoria_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/4-3.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-640x640.jpg\" class=\"\" alt=\"Concert_square_Victoria_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/2-3.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                                        <div class=\"swiper-slide || relative\">\n                                <div class=\"thumbnail w-full rounded-[16px] lg:rounded-[20px]\"  style=\"padding-bottom: 100%\" >\n      <img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-640x640.jpg\" class=\"\" alt=\"Concert_square_Victoria_\u00e9t\u00e9_2024\" srcset=\"https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-640x640.jpg 640w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-300x300.jpg 300w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-1024x1024.jpg 1024w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-150x150.jpg 150w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-768x768.jpg 768w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-480x480.jpg 480w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4-350x350.jpg 350w, https:\/\/montrealcentreville.ca\/wp-content\/uploads\/2024\/07\/1-4.jpg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>  <\/div>                <\/div>\n                    <\/div>\n            <div class=\"mt-16 flex items-center justify-between\">\n                <div class=\"carousel-buttons || flex items-center justify-center\">\n                    <button title=\"Bouton pr\u00e9c\u00e9dent\" class=\"simple left-button || group relative overflow-hidden rotate-180 bg-[var(--color)] rounded-full aspect-square w-[50px] || lg:w-16 2xl:w-20\">\n                        <span class=\"absolute inset-1\/2 left-[calc(50%-7px)] top-[calc(50%-7px)] w-full h-full -translate-x-3 opacity-0 [transition:_transform_300ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)] group-hover:translate-x-0 group-hover:opacity-100 group-hover:[transition:_transform_500ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)]\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\">\n<path d=\"M11.4 7.85149C11.2728 7.84818 11.2003 7.84481 11.1277 7.8445C7.848 7.84766 4.56831 7.85082 1.28862 7.85552C0.946095 7.85589 0.66109 7.74964 0.486904 7.43822C0.318101 7.13598 0.324011 6.82781 0.502728 6.53249C0.672624 6.25136 0.940954 6.14336 1.25967 6.14302C1.90324 6.14156 2.54682 6.14086 3.19077 6.14055C5.83342 6.13769 8.47607 6.13484 11.1187 6.13428C11.1921 6.13459 11.2654 6.15559 11.3388 6.16662C11.348 6.14285 11.3572 6.11908 11.3664 6.0953C11.3126 6.0417 11.2591 5.98848 11.2053 5.93488C9.95373 4.68786 8.70134 3.44161 7.45203 2.19229C7.3475 2.08815 7.24643 1.97289 7.17567 1.84495C6.9838 1.49905 7.09253 1.07348 7.42141 0.810572C7.77562 0.527706 8.1815 0.526117 8.51541 0.809007C8.5669 0.852646 8.61378 0.901656 8.66182 0.949515C10.4649 2.74596 12.268 4.5424 14.071 6.33884C14.4876 6.75387 14.4887 7.21841 14.0743 7.63281C12.2598 9.44734 10.446 11.2626 8.6311 13.076C8.17066 13.5365 7.59462 13.4827 7.23442 12.9514C7.04413 12.6707 7.0408 12.3365 7.23489 12.0587C7.30393 11.9598 7.38642 11.8681 7.47237 11.7821C8.71595 10.5363 9.96107 9.29191 11.2058 8.04718C11.258 7.995 11.3102 7.94281 11.4007 7.85226L11.4 7.85149Z\" fill=\"#3D43B5\"\/>\n<\/svg><\/span>\n                        <span class=\"absolute inset-1\/2 left-[calc(50%-7px)] top-[calc(50%-7px)] w-full h-full [transition:_transform_300ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)] group-hover:translate-x-3 group-hover:opacity-0 group-hover:[transition:_transform_500ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)]\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\">\n<path d=\"M11.4 7.85149C11.2728 7.84818 11.2003 7.84481 11.1277 7.8445C7.848 7.84766 4.56831 7.85082 1.28862 7.85552C0.946095 7.85589 0.66109 7.74964 0.486904 7.43822C0.318101 7.13598 0.324011 6.82781 0.502728 6.53249C0.672624 6.25136 0.940954 6.14336 1.25967 6.14302C1.90324 6.14156 2.54682 6.14086 3.19077 6.14055C5.83342 6.13769 8.47607 6.13484 11.1187 6.13428C11.1921 6.13459 11.2654 6.15559 11.3388 6.16662C11.348 6.14285 11.3572 6.11908 11.3664 6.0953C11.3126 6.0417 11.2591 5.98848 11.2053 5.93488C9.95373 4.68786 8.70134 3.44161 7.45203 2.19229C7.3475 2.08815 7.24643 1.97289 7.17567 1.84495C6.9838 1.49905 7.09253 1.07348 7.42141 0.810572C7.77562 0.527706 8.1815 0.526117 8.51541 0.809007C8.5669 0.852646 8.61378 0.901656 8.66182 0.949515C10.4649 2.74596 12.268 4.5424 14.071 6.33884C14.4876 6.75387 14.4887 7.21841 14.0743 7.63281C12.2598 9.44734 10.446 11.2626 8.6311 13.076C8.17066 13.5365 7.59462 13.4827 7.23442 12.9514C7.04413 12.6707 7.0408 12.3365 7.23489 12.0587C7.30393 11.9598 7.38642 11.8681 7.47237 11.7821C8.71595 10.5363 9.96107 9.29191 11.2058 8.04718C11.258 7.995 11.3102 7.94281 11.4007 7.85226L11.4 7.85149Z\" fill=\"#3D43B5\"\/>\n<\/svg><\/span>\n                    <\/button>\n                    <button title=\"Bouton suivant\" class=\"simple right-button || group relative overflow-hidden bg-[var(--color)] rounded-full aspect-square w-[50px] || lg:w-16 2xl:w-20\">\n                        <span class=\"absolute inset-1\/2 left-[calc(50%-7px)] top-[calc(50%-7px)] w-full h-full -translate-x-3 opacity-0 [transition:_transform_300ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)] group-hover:translate-x-0 group-hover:opacity-100 group-hover:[transition:_transform_500ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)]\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\">\n<path d=\"M11.4 7.85149C11.2728 7.84818 11.2003 7.84481 11.1277 7.8445C7.848 7.84766 4.56831 7.85082 1.28862 7.85552C0.946095 7.85589 0.66109 7.74964 0.486904 7.43822C0.318101 7.13598 0.324011 6.82781 0.502728 6.53249C0.672624 6.25136 0.940954 6.14336 1.25967 6.14302C1.90324 6.14156 2.54682 6.14086 3.19077 6.14055C5.83342 6.13769 8.47607 6.13484 11.1187 6.13428C11.1921 6.13459 11.2654 6.15559 11.3388 6.16662C11.348 6.14285 11.3572 6.11908 11.3664 6.0953C11.3126 6.0417 11.2591 5.98848 11.2053 5.93488C9.95373 4.68786 8.70134 3.44161 7.45203 2.19229C7.3475 2.08815 7.24643 1.97289 7.17567 1.84495C6.9838 1.49905 7.09253 1.07348 7.42141 0.810572C7.77562 0.527706 8.1815 0.526117 8.51541 0.809007C8.5669 0.852646 8.61378 0.901656 8.66182 0.949515C10.4649 2.74596 12.268 4.5424 14.071 6.33884C14.4876 6.75387 14.4887 7.21841 14.0743 7.63281C12.2598 9.44734 10.446 11.2626 8.6311 13.076C8.17066 13.5365 7.59462 13.4827 7.23442 12.9514C7.04413 12.6707 7.0408 12.3365 7.23489 12.0587C7.30393 11.9598 7.38642 11.8681 7.47237 11.7821C8.71595 10.5363 9.96107 9.29191 11.2058 8.04718C11.258 7.995 11.3102 7.94281 11.4007 7.85226L11.4 7.85149Z\" fill=\"#3D43B5\"\/>\n<\/svg><\/span>\n                        <span class=\"absolute inset-1\/2 left-[calc(50%-7px)] top-[calc(50%-7px)] w-full h-full [transition:_transform_300ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)] group-hover:translate-x-3 group-hover:opacity-0 group-hover:[transition:_transform_500ms_cubic-bezier(0.4,_0,_0.2,_1),_opacity_250ms_cubic-bezier(0.4,_0,_0.2,_1)]\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\">\n<path d=\"M11.4 7.85149C11.2728 7.84818 11.2003 7.84481 11.1277 7.8445C7.848 7.84766 4.56831 7.85082 1.28862 7.85552C0.946095 7.85589 0.66109 7.74964 0.486904 7.43822C0.318101 7.13598 0.324011 6.82781 0.502728 6.53249C0.672624 6.25136 0.940954 6.14336 1.25967 6.14302C1.90324 6.14156 2.54682 6.14086 3.19077 6.14055C5.83342 6.13769 8.47607 6.13484 11.1187 6.13428C11.1921 6.13459 11.2654 6.15559 11.3388 6.16662C11.348 6.14285 11.3572 6.11908 11.3664 6.0953C11.3126 6.0417 11.2591 5.98848 11.2053 5.93488C9.95373 4.68786 8.70134 3.44161 7.45203 2.19229C7.3475 2.08815 7.24643 1.97289 7.17567 1.84495C6.9838 1.49905 7.09253 1.07348 7.42141 0.810572C7.77562 0.527706 8.1815 0.526117 8.51541 0.809007C8.5669 0.852646 8.61378 0.901656 8.66182 0.949515C10.4649 2.74596 12.268 4.5424 14.071 6.33884C14.4876 6.75387 14.4887 7.21841 14.0743 7.63281C12.2598 9.44734 10.446 11.2626 8.6311 13.076C8.17066 13.5365 7.59462 13.4827 7.23442 12.9514C7.04413 12.6707 7.0408 12.3365 7.23489 12.0587C7.30393 11.9598 7.38642 11.8681 7.47237 11.7821C8.71595 10.5363 9.96107 9.29191 11.2058 8.04718C11.258 7.995 11.3102 7.94281 11.4007 7.85226L11.4 7.85149Z\" fill=\"#3D43B5\"\/>\n<\/svg><\/span>\n                    <\/button>\n                <\/div>\n                                    <div class=\"swiper-pagination || !relative !bottom-0 !top-0 !left-0 !w-auto flex items-center\"><\/div>\n                            <\/div>\n        <\/div>\n        <\/div>\n    <\/section>\n","protected":false},"featured_media":10300,"template":"","what-to-do-category":[31],"what-to-do-type":[69,68,67,70],"class_list":["post-10303","what-to-do","type-what-to-do","status-publish","has-post-thumbnail","hentry","what-to-do-category-have-fun","what-to-do-type-worker","what-to-do-type-visitor","what-to-do-type-student","what-to-do-type-resident-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/what-to-do\/10303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/what-to-do"}],"about":[{"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/types\/what-to-do"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/media\/10300"}],"wp:attachment":[{"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/media?parent=10303"}],"wp:term":[{"taxonomy":"what-to-do-category","embeddable":true,"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/what-to-do-category?post=10303"},{"taxonomy":"what-to-do-type","embeddable":true,"href":"https:\/\/montrealcentreville.ca\/en\/wp-json\/wp\/v2\/what-to-do-type?post=10303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}